{"id":5002,"date":"2022-09-14T13:02:17","date_gmt":"2022-09-14T11:02:17","guid":{"rendered":"https:\/\/cecluxembourg.addedsense.eu\/themen\/reisen\/voyage-a-forfait\/"},"modified":"2026-03-10T23:08:52","modified_gmt":"2026-03-10T22:08:52","slug":"pauschalreise","status":"publish","type":"page","link":"https:\/\/www.cecluxembourg.lu\/de\/themen\/reisen\/pauschalreise\/","title":{"rendered":"Pauschalreise"},"content":{"rendered":"\n\n\tEine Pauschalreise ist eine Kombination aus mindestens zwei verschiedenen Reiseleistungen, die von einem Reiseanbieter f\u00fcr eine bestimmte Reise angeboten werden. Dabei kann es sich um ein vorgefertigtes &#8222;Gesamtpaket&#8220; handeln oder um eine Zusammenstellung einzelner Reiseleistungen, die vom Reiseanbieter als Paket verkauft werden. Pauschalreisen sind grunds\u00e4tzlich von &#8222;verbundenen Reiseleistungen&#8220; zu unterscheiden (siehe unten).<br \/>\nSeit dem 25. November 2015 werden die Rechte von Verbrauchern, die eine Pauschalreise buchen, durch die EU-Pauschalreiserichtlinie (<a href=\"https:\/\/eur-lex.europa.eu\/legal-content\/DE\/TXT\/?uri=CELEX%3A32015L2302\" target=\"_blank\" rel=\"noopener\">Richtlinie (EU) 2015\/2302<\/a>) gest\u00e4rkt.\nIn Luxemburg wurde die Richtlinie durch das Gesetz vom 25. April 2018 \u201ezur \u00c4nderung des Verbrauchergesetzbuches \u00fcber Pauschalreisen und verbundene Reiseleistungen und zur Umsetzung in das nationale Recht der Richtlinie (EU) 2015\/2302 des Europ\u00e4ischen Parlaments und des Rates vom 25.11.2015 \u00fcber Pauschalreisen und verbundene Reiseleistungen&#8220; umgesetzt und gilt f\u00fcr alle Vertr\u00e4ge, die ab dem 1. Juli 2018 geschlossen werden.<br \/>\nDie EU-Pauschalreiserichtlinie regelt unter anderem folgende Rechte und Pflichten:\n<h2>Vorvertragliche Informationspflichten<\/h2>\n<p>Vor Vertragsabschluss muss der Reisende vom Reiseanbieter alle wesentlichen Informationen \u00fcber die Reise, wie beispielsweise Preis, Reisedaten und Reiseziel erhalten. Dar\u00fcber hinaus ist ihm ein entsprechendes Standardinformationsblatt auszuh\u00e4ndigen. Diese Informationspflicht obliegt sowohl dem Reiseveranstalter als auch dem Reisevermittler (z. B. dem Reiseb\u00fcro), der die Reise verkauft.<\/p>\n<h2>\u00c4nderungen vor Reisebeginn<\/h2>\n<p>Nach Abschluss des Pauschalreisevertrages darf der Reiseveranstalter den Preis nur erh\u00f6hen, wenn er sich dieses Recht im Vertrag vorbehalten hat. Eine Preiserh\u00f6hung ist grunds\u00e4tzlich nur zul\u00e4ssig, wenn sie auf eine Erh\u00f6hung der Transportkosten (z.B. Erh\u00f6hung des Treibstoffpreises), des Wechselkurses oder entsprechender Steuern und Abgaben (z.B. Kurtaxe) zur\u00fcckzuf\u00fchren ist. Der Reiseveranstalter muss den Reisenden sp\u00e4testens 20 Tage vor Beginn der Reise \u00fcber die Preiserh\u00f6hung informieren.<\/p>\n<p>Andere Vertragsbedingungen darf der Reiseveranstalter nur dann einseitig \u00e4ndern, wenn er sich dieses Recht ausdr\u00fccklich im Vertrag vorbehalten hat, die \u00c4nderungen unerheblich sind und der Reiseveranstalter den Reisenden \u00fcber die \u00c4nderung entsprechend informiert hat.<\/p>\n<p>Wenn der Reiseveranstalter vor Reisebeginn wesentliche Vertragsbedingungen \u00e4ndert oder den Reisepreis um mehr als 8 % des Gesamtpreises der Pauschalreise erh\u00f6ht, hat der Reisende grunds\u00e4tzlich das Recht, innerhalb einer angemessenen Frist ohne Zahlung einer entsprechenden R\u00fccktrittsgeb\u00fchr vom Vertrag zur\u00fcckzutreten.<\/p>\n<p>Dar\u00fcber hinaus ist der Reisende berechtigt, die Reise jederzeit vor Reisebeginn zu stornieren. Jedoch kann der Reiseveranstalter in diesem Fall eine (angemessene) R\u00fccktrittsgeb\u00fchr vom Reisenden verlangen.<\/p>\n<p>Der Reisende hat die M\u00f6glichkeit, den Pauschalreisevertrag vor Beginn der Reise auf eine andere Person, die alle Vertragsbedingungen erf\u00fcllt, zu \u00fcbertragen. Der Reisende muss den Reiseveranstalter mindestens 7 Tage vor Reisebeginn \u00fcber die Abtretung informieren. Der Reisende, der die Pauschalreise abgetreten hat und die Person, die in den Vertrag eingetreten ist, haften dem Veranstalter gegen\u00fcber gesamtschuldnerisch f\u00fcr eventuell noch ausstehende Betr\u00e4ge sowie f\u00fcr die durch die Abtretung entstandenen Mehrkosten.<\/p>\n<h2>W\u00e4hrend der Reise<\/h2>\n<p>Der Reiseveranstalter haftet f\u00fcr die Erbringung der vereinbarten Reiseleistungen, unabh\u00e4ngig davon, ob er selbst oder ein Dritter die Leistungen zu erbringen hat. Kann ein wesentlicher Teil der vereinbarten Reiseleistung nicht wie vereinbart erbracht werden, so hat der Reiseveranstalter dem Reisenden ohne Aufpreis eine mindestens gleichwertige Ersatzleistung anzubieten. Bietet der Reiseveranstalter dem Reisenden keine oder nur eine minderwertige Ersatzleistung an, so kann der Reisende eine entsprechende Preisminderung verlangen.<\/p>\n<p>Treten w\u00e4hrend der Reise Probleme auf, so hat der Reisende den Reiseveranstalter unverz\u00fcglich \u00fcber die aufgetretenen Missst\u00e4nde zu informieren.<\/p>\n<h2>Im Falle einer Insolvenz des Reiseveranstalters<\/h2>\n<p>Um den Reisenden vor einer m\u00f6glichen Insolvenz des Reiseveranstalters zu sch\u00fctzen, ist der Reiseveranstalter verpflichtet, eine entsprechende Insolvenzversicherung abzuschlie\u00dfen. Im Falle der Insolvenz erstattet diese dem Reisenden bereits geleistete Zahlungen f\u00fcr Leistungen, die aufgrund der Insolvenz des Reiseveranstalters nicht erbracht wurden. Beinhaltet die gebuchte Pauschalreise auch eine entsprechende Bef\u00f6rderung (z.B. Fl\u00fcge), muss der Reiseveranstalter auch den R\u00fccktransport des Reisenden im Falle einer Insolvenz absichern.<\/p>\n<h2>Verbundene Reiseleistungen<\/h2>\n<p>Immer mehr Verbraucher stellen sich ihre Reisen selbst zusammen, indem sie verschiedene Reiseleistungen von unterschiedlichen Anbietern kombinieren. So kann der Reisende beispielsweise bei der Buchung eines Fluges im Internet \u00fcber einen Link bei einem anderen Anbieter einen Hotelaufenthalt oder einen Mietwagen buchen. Schlie\u00dft der Reisende einen solchen Vertrag ab, ist der Reiseveranstalter verpflichtet, den Reisenden darauf hinzuweisen, dass die Vorschriften f\u00fcr Pauschalreisen nicht anwendbar sind. Grunds\u00e4tzlich ist der Reisveranstalter aber auch bei &#8222;verbundenen Reiseleistungen&#8220; verpflichtet, eine entsprechende Insolvenzversicherung abzuschlie\u00dfen. Bei Problemen hat sich der Reisende an den jeweiligen Anbieter der betreffenden Reiseleistung zu wenden.<\/p>\n   <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"youtube-content-blocker\" data-borlabs-cookie-content=\"PGlmcmFtZSBzcmM9Imh0dHBzOi8vd3d3LnlvdXR1YmUtbm9jb29raWUuY29tL2VtYmVkL2wwZXJZbHB6SzNFP3JlbD0wIiBhbGxvd2Z1bGxzY3JlZW4+PC9pZnJhbWU+\"><div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-youtube\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/www.cecluxembourg.lu\/wp-content\/uploads\/borlabs-cookie\/1\/yt_l0erYlpzK3E_hqdefault.jpg')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-play-button\"><\/div> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>YouTube<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf die Schaltfl\u00e4che unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Mehr Informationen<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <\/div> <\/div><\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Eine Pauschalreise ist eine Kombination aus mindestens zwei verschiedenen Reiseleistungen, die von einem Reiseanbieter f\u00fcr eine bestimmte Reise angeboten werden. Dabei kann es sich um ein vorgefertigtes &#8222;Gesamtpaket&#8220; handeln oder um eine Zusammenstellung einzelner Reiseleistungen, die vom Reiseanbieter als Paket verkauft werden. Pauschalreisen sind grunds\u00e4tzlich von &#8222;verbundenen Reiseleistungen&#8220; zu unterscheiden (siehe unten). Seit dem 25.&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":4971,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5002","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pauschalreise - Europ\u00e4ische Verbraucherzentrum Luxemburg<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cecluxembourg.lu\/de\/themen\/reisen\/pauschalreise\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pauschalreise - Europ\u00e4ische Verbraucherzentrum Luxemburg\" \/>\n<meta property=\"og:description\" content=\"Eine Pauschalreise ist eine Kombination aus mindestens zwei verschiedenen Reiseleistungen, die von einem Reiseanbieter f\u00fcr eine bestimmte Reise angeboten werden. Dabei kann es sich um ein vorgefertigtes &#8222;Gesamtpaket&#8220; handeln oder um eine Zusammenstellung einzelner Reiseleistungen, die vom Reiseanbieter als Paket verkauft werden. Pauschalreisen sind grunds\u00e4tzlich von &#8222;verbundenen Reiseleistungen&#8220; zu unterscheiden (siehe unten). Seit dem 25.&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cecluxembourg.lu\/de\/themen\/reisen\/pauschalreise\/\" \/>\n<meta property=\"og:site_name\" content=\"Europ\u00e4ische Verbraucherzentrum Luxemburg\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-10T22:08:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cecluxembourg.lu\\\/de\\\/themen\\\/reisen\\\/pauschalreise\\\/\",\"url\":\"https:\\\/\\\/www.cecluxembourg.lu\\\/de\\\/themen\\\/reisen\\\/pauschalreise\\\/\",\"name\":\"Pauschalreise - Europ\u00e4ische Verbraucherzentrum Luxemburg\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cecluxembourg.lu\\\/#website\"},\"datePublished\":\"2022-09-14T11:02:17+00:00\",\"dateModified\":\"2026-03-10T22:08:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cecluxembourg.lu\\\/de\\\/themen\\\/reisen\\\/pauschalreise\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cecluxembourg.lu\\\/de\\\/themen\\\/reisen\\\/pauschalreise\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cecluxembourg.lu\\\/de\\\/themen\\\/reisen\\\/pauschalreise\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Themen\",\"item\":\"https:\\\/\\\/www.cecluxembourg.lu\\\/de\\\/themen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reisen\",\"item\":\"https:\\\/\\\/www.cecluxembourg.lu\\\/de\\\/themen\\\/reisen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pauschalreise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cecluxembourg.lu\\\/#website\",\"url\":\"https:\\\/\\\/www.cecluxembourg.lu\\\/\",\"name\":\"Europ\u00e4ische Verbraucherzentrum Luxemburg\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cecluxembourg.lu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cecluxembourg.lu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cecluxembourg.lu\\\/#organization\",\"name\":\"Europ\u00e4ische Verbraucherzentrum Luxemburg\",\"url\":\"https:\\\/\\\/www.cecluxembourg.lu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.cecluxembourg.lu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cecluxembourg.lu\\\/wp-content\\\/uploads\\\/logo-cecluxembourg-fr2.svg\",\"contentUrl\":\"https:\\\/\\\/www.cecluxembourg.lu\\\/wp-content\\\/uploads\\\/logo-cecluxembourg-fr2.svg\",\"width\":444,\"height\":186,\"caption\":\"Europ\u00e4ische Verbraucherzentrum Luxemburg\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cecluxembourg.lu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pauschalreise - Europ\u00e4ische Verbraucherzentrum Luxemburg","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cecluxembourg.lu\/de\/themen\/reisen\/pauschalreise\/","og_locale":"de_DE","og_type":"article","og_title":"Pauschalreise - Europ\u00e4ische Verbraucherzentrum Luxemburg","og_description":"Eine Pauschalreise ist eine Kombination aus mindestens zwei verschiedenen Reiseleistungen, die von einem Reiseanbieter f\u00fcr eine bestimmte Reise angeboten werden. Dabei kann es sich um ein vorgefertigtes &#8222;Gesamtpaket&#8220; handeln oder um eine Zusammenstellung einzelner Reiseleistungen, die vom Reiseanbieter als Paket verkauft werden. Pauschalreisen sind grunds\u00e4tzlich von &#8222;verbundenen Reiseleistungen&#8220; zu unterscheiden (siehe unten). Seit dem 25.&hellip;","og_url":"https:\/\/www.cecluxembourg.lu\/de\/themen\/reisen\/pauschalreise\/","og_site_name":"Europ\u00e4ische Verbraucherzentrum Luxemburg","article_modified_time":"2026-03-10T22:08:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cecluxembourg.lu\/de\/themen\/reisen\/pauschalreise\/","url":"https:\/\/www.cecluxembourg.lu\/de\/themen\/reisen\/pauschalreise\/","name":"Pauschalreise - Europ\u00e4ische Verbraucherzentrum Luxemburg","isPartOf":{"@id":"https:\/\/www.cecluxembourg.lu\/#website"},"datePublished":"2022-09-14T11:02:17+00:00","dateModified":"2026-03-10T22:08:52+00:00","breadcrumb":{"@id":"https:\/\/www.cecluxembourg.lu\/de\/themen\/reisen\/pauschalreise\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cecluxembourg.lu\/de\/themen\/reisen\/pauschalreise\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cecluxembourg.lu\/de\/themen\/reisen\/pauschalreise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Themen","item":"https:\/\/www.cecluxembourg.lu\/de\/themen\/"},{"@type":"ListItem","position":2,"name":"Reisen","item":"https:\/\/www.cecluxembourg.lu\/de\/themen\/reisen\/"},{"@type":"ListItem","position":3,"name":"Pauschalreise"}]},{"@type":"WebSite","@id":"https:\/\/www.cecluxembourg.lu\/#website","url":"https:\/\/www.cecluxembourg.lu\/","name":"Europ\u00e4ische Verbraucherzentrum Luxemburg","description":"","publisher":{"@id":"https:\/\/www.cecluxembourg.lu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cecluxembourg.lu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.cecluxembourg.lu\/#organization","name":"Europ\u00e4ische Verbraucherzentrum Luxemburg","url":"https:\/\/www.cecluxembourg.lu\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.cecluxembourg.lu\/#\/schema\/logo\/image\/","url":"https:\/\/www.cecluxembourg.lu\/wp-content\/uploads\/logo-cecluxembourg-fr2.svg","contentUrl":"https:\/\/www.cecluxembourg.lu\/wp-content\/uploads\/logo-cecluxembourg-fr2.svg","width":444,"height":186,"caption":"Europ\u00e4ische Verbraucherzentrum Luxemburg"},"image":{"@id":"https:\/\/www.cecluxembourg.lu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.cecluxembourg.lu\/de\/wp-json\/wp\/v2\/pages\/5002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cecluxembourg.lu\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cecluxembourg.lu\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cecluxembourg.lu\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cecluxembourg.lu\/de\/wp-json\/wp\/v2\/comments?post=5002"}],"version-history":[{"count":3,"href":"https:\/\/www.cecluxembourg.lu\/de\/wp-json\/wp\/v2\/pages\/5002\/revisions"}],"predecessor-version":[{"id":13929,"href":"https:\/\/www.cecluxembourg.lu\/de\/wp-json\/wp\/v2\/pages\/5002\/revisions\/13929"}],"up":[{"embeddable":true,"href":"https:\/\/www.cecluxembourg.lu\/de\/wp-json\/wp\/v2\/pages\/4971"}],"wp:attachment":[{"href":"https:\/\/www.cecluxembourg.lu\/de\/wp-json\/wp\/v2\/media?parent=5002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}